{"id":241260,"date":"2021-04-10T11:16:00","date_gmt":"2021-04-10T09:16:00","guid":{"rendered":"https:\/\/allegro234.net\/?p=241260"},"modified":"2021-08-24T11:26:29","modified_gmt":"2021-08-24T09:26:29","slug":"el-proposito-importa-por-lo-que-se-hace-no-por-lo-que-se-dice","status":"publish","type":"post","link":"https:\/\/allegro234.net\/es\/purpose-matters-by-what-you-do-not-by-what-you-say\/","title":{"rendered":"El prop\u00f3sito importa por lo que haces, no por lo que dices"},"content":{"rendered":"<h2 class=\"wp-block-heading\">La finalidad es una parte inherente de la empresa<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Desde el principio de los tiempos, el prop\u00f3sito nace con la empresa expresando su raz\u00f3n de ser.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, el prop\u00f3sito debe estar conectado con el negocio, y su encaje se consigue porque los objetivos estrat\u00e9gicos nacen de dicho negocio y est\u00e1n alineados con \u00e9l.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El reto para la C-Suite y el nivel directivo es comprender primero el significado real y m\u00e1s profundo del prop\u00f3sito de la empresa, traduci\u00e9ndolo en una misi\u00f3n y una visi\u00f3n procesables. Es una cuesti\u00f3n de alineaci\u00f3n, coherencia y consistencia. \u00c9stas son la base de un mejor rendimiento de la empresa, no s\u00f3lo en cuanto a la consecuci\u00f3n de mejores resultados econ\u00f3micos y financieros, sino tambi\u00e9n en cuanto a la generaci\u00f3n de un impacto positivo. BTW, si el equipo directivo considera que el prop\u00f3sito no es suficientemente representativo de la actividad de la empresa, o tienen un problema, o ellos son el problema.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>El prop\u00f3sito debe integrarse en todos los aspectos de la actividad empresarial.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Como la vida, el prop\u00f3sito se entiende hacia atr\u00e1s; pero debe vivirse hacia delante. Esto significa que, si el prop\u00f3sito cambia, la empresa debe cambiar, esencialmente, porque tiene que ser reimaginada, redise\u00f1ada y reiniciada para vivir un nuevo futuro aspiracional.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Hacer expl\u00edcito el prop\u00f3sito es un buen primer paso<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para ser pr\u00e1cticos, un buen primer paso es explicitar el prop\u00f3sito y, si ya existe, asegurarse de que realmente es la raz\u00f3n de ser de la empresa y no una buena narrativa inventada por las \u00e1reas de marketing o comunicaci\u00f3n.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a1Lidia con ello! Si el objetivo del negocio es s\u00f3lo ganar dinero, \u00a1eso es lo que es! Como ya se ha dicho, puede cambiar si cambia el negocio.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Para reforzar, profundizar y, sobre todo, dejarse llevar por un prop\u00f3sito, adem\u00e1s de hacerlo expl\u00edcito, las empresas deben traducirlo continuamente en objetivos empresariales precisos asociados a \u00e9l. Esto garantiza una respuesta ejecutiva a todas las partes interesadas y se convierte en el detonante de una transformaci\u00f3n y un crecimiento excepcionales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para hacer de la finalidad una experiencia cotidiana significativa, es clave<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Piensa, act\u00faa y di, en ese orden<\/li><li>Medir el impacto de la actuaci\u00f3n de la empresa sobre el prop\u00f3sito<\/li><li>Responsabiliza al equipo directivo<\/li><li>Garantizar que todas las partes interesadas comprendan y compartan la raz\u00f3n de ser de la empresa<\/li><li>Construir los s\u00edmbolos, rituales e historias de la empresa en torno a su finalidad<\/li><\/ul>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>No dejes que el marketing invente un prop\u00f3sito de marca extravagante, la gente no es idiota.<\/p><\/blockquote>\n\n\n\n<h2 class=\"wp-block-heading\">Marca y finalidad<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El branding pretende construir un significado realista de la empresa en su interacci\u00f3n con las personas, independientemente pero incluyendo el papel que desempe\u00f1an como ciudadanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, cuando el prop\u00f3sito incluye el impacto en la sociedad y el medio ambiente, la marca como plataforma empresarial ayuda a demostrar la conciencia de la empresa, por no mencionar las cuestiones internas de gobernanza e inversiones responsables.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando las partes interesadas comprenden, viven y comparten lo que la empresa representa y por qu\u00e9 es importante, los resultados llegan por s\u00ed solos, sin esfuerzos fuera de lo normal. Por eso dije, al principio de este art\u00edculo, que las empresas que act\u00faan en consonancia con su prop\u00f3sito crean valor, generan resultados superiores e incluso podr\u00edan tener un impacto positivo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Si la empresa no puede cumplir su prop\u00f3sito, su promesa de marca es b\u00e1sicamente una tonter\u00eda vac\u00eda.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Surgen algunas preguntas:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00bfD\u00f3nde se encuentra tu empresa y tu marca en este viaje hacia las marcas con conciencia?<\/li><li>\u00bfEs expl\u00edcita la finalidad de la empresa y necesita transformarse?<\/li><li>\u00bfEst\u00e1 la empresa preparada para una transformaci\u00f3n que la lleve a crecer tanto en resultados como en impacto?<\/li><\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">\u00bfTe interesa explicitar tu prop\u00f3sito y reforzar tu estrategia de marca? Hablemos para ver c\u00f3mo tu empresa puede afrontar la transformaci\u00f3n y crecer de forma saludable.<\/h4>","protected":false},"excerpt":{"rendered":"<p>El prop\u00f3sito debe integrarse en todos los aspectos de la actividad empresarial.<\/p>","protected":false},"author":2,"featured_media":241270,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[548],"tags":[400,419,291,339],"class_list":["post-241260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-branding","tag-allegro-234-2","tag-brands-with-a-conscience","tag-conscience","tag-purpose"],"_links":{"self":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts\/241260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/comments?post=241260"}],"version-history":[{"count":0,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts\/241260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/media\/241270"}],"wp:attachment":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/media?parent=241260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/categories?post=241260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/tags?post=241260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}