{"id":4673,"date":"2008-03-20T13:10:00","date_gmt":"2008-03-20T12:10:00","guid":{"rendered":"https:\/\/allegro234.net\/belonging-values-could-be-self-expression-valuescouldnt-them\/"},"modified":"2026-06-26T21:28:59","modified_gmt":"2026-06-26T19:28:59","slug":"los-valores-de-pertenencia-podrian-ser-valores-de-autoexpresion-no","status":"publish","type":"post","link":"https:\/\/allegro234.net\/es\/belonging-values-could-be-self-expression-valuescouldnt-them\/","title":{"rendered":"Los valores de pertenencia podr\u00edan ser valores de autoexpresi\u00f3n\"\u00a6\u00bfo no?"},"content":{"rendered":"<p>Parece una pregunta canadiense\" y, en realidad, \u00a1lo es!... La raz\u00f3n es que estoy utilizando dos grandes ejemplos de anuncios canadienses. Ambos son de la cerveza Molson, ambos se basan en valores de pertenencia\"\u00a6 ambos potencian la autoexpresi\u00f3n.<\/p>\n<p>Esto podr\u00eda considerarse una dicotom\u00eda. Por definici\u00f3n, existen dos grandes familias (perm\u00edteme decirlo as\u00ed) de valores, los de pertenencia y los de autoexpresi\u00f3n.<\/p>\n<p>Si ves el primer anuncio, descubrir\u00e1s claramente los valores relacionados con la naci\u00f3n, los valores clave y los comportamientos de su gente\"\u00a6<\/p>\n<div>\n<div style=\"text-align: center;\"><object data=\"http:\/\/www.youtube.com\/v\/fmvMCeWiG6w\" type=\"application\/x-shockwave-flash\" width=\"425\" height=\"350\"><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/fmvMCeWiG6w\" \/><\/object><\/div>\n<\/div>\n<div>\n<p>Si ves este segundo, muestran por contraposici\u00f3n, valores que tienen y les hacen diferentes de los americanos\"\u00a6 Son canadienses o como dijo Joe, yo soy canadiense\"\u00a6<\/p>\n<div>\n<div style=\"text-align: center;\"><object data=\"http:\/\/www.youtube.com\/v\/y9gvbThmETY\" type=\"application\/x-shockwave-flash\" width=\"425\" height=\"350\"><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/y9gvbThmETY\" \/><\/object><\/div>\n<\/div>\n<p>As\u00ed la mesa est\u00e1 servida\"\u00a6 El sentido y la sensibilidad est\u00e1n presentes\"\u00a6 Una fuerte identidad est\u00e1 detr\u00e1s de la escena\"\u00a6 la imagen de marca est\u00e1 ah\u00ed s\u00f3lo un segundo\"\u00a6 Molson\"\u00a6<\/p>\n<p>\u00bfPodr\u00edamos considerar que en los \"Bienes de Consumo de Movimiento R\u00e1pido\", las tribus se basan en esta exquisita relaci\u00f3n entre los valores de pertenencia y de autoexpresi\u00f3n?<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>It looks like a Canadian question&#8221; and actually, it is!&#8230; The reason why is because I&#8217;m using two great examples of Canadian ads. Both are from Molson beer, both are based on belonging values&#8221;\u00a6 both are empowering self-expression. This could be consider as a dichotomy. By definition, there are two main families (allow me to [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[542],"tags":[55,34,63,35,64],"class_list":["post-4673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing","tag-brand","tag-branding","tag-canada","tag-cristian-saracco","tag-molson"],"_links":{"self":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts\/4673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/comments?post=4673"}],"version-history":[{"count":0,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts\/4673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/media\/5541"}],"wp:attachment":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/media?parent=4673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/categories?post=4673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/tags?post=4673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}