{"id":4674,"date":"2008-03-26T13:11:00","date_gmt":"2008-03-26T12:11:00","guid":{"rendered":"https:\/\/allegro234.net\/branding-did-you-say-branding\/"},"modified":"2021-10-27T17:37:11","modified_gmt":"2021-10-27T15:37:11","slug":"branding-has-dicho-branding","status":"publish","type":"post","link":"https:\/\/allegro234.net\/es\/branding-did-you-say-branding\/","title":{"rendered":"Branding... \u00bfHas dicho branding?"},"content":{"rendered":"<p>Hoy, en el blog de Javier Velilla, ha colgado este v\u00eddeo de <a title=\"Cien monos\" href=\"http:\/\/www.ahundredmonkeys.com\/\" target=\"_blank\" rel=\"noopener nofollow\">Cien Monos<\/a> que trata de explicar qu\u00e9 es el Branding... Est\u00e1 bastante bien.<\/p>\n<div>\n<div style=\"text-align: center;\"><object data=\"http:\/\/www.youtube.com\/v\/AwzNXYoitLo\" type=\"application\/x-shockwave-flash\" width=\"425\" height=\"355\"><param name=\"wmode\" value=\"transparent\" \/><param name=\"src\" value=\"http:\/\/www.youtube.com\/v\/AwzNXYoitLo\" \/><\/object><\/div>\n<\/div>\n<p>Adem\u00e1s, como ha dicho Nicholas Ind, hay muchas definiciones de marcas y branding. Hay quien piensa que una marca es un logotipo. O la publicidad. O un envoltorio. U otra palabra para el nombre del producto y servicio que compran. En realidad es todo eso y mucho m\u00e1s.<\/p>\n<p>Para hacerte una idea de lo que es una marca, p\u00e1rate a pensar como un cliente. Compro zapatillas deportivas Nike y ordenadores Apple, vuelo con Virgin, compro en Amazon, sue\u00f1o con tener un Ferrari y dono dinero a Unicef porque me gusta lo que estas \"\u02dcbrands' representan. Vuelo con Virgin por la calidad de la experiencia, el aspecto y el tacto de los aviones y la forma en que me trata el personal de facturaci\u00f3n y de a bordo. Del mismo modo, compro ordenadores Apple por la calidad del hardware y el software, la posici\u00f3n de la marca como externa y la experiencia en la tienda. Nunca he comprado ni comprar\u00e9 ning\u00fan otro ordenador. Poseer un Apple es algo emocional.<\/p>","protected":false},"excerpt":{"rendered":"<p>Today, in Javier Velilla&#8217;s blog, he posted this video from Hundred Monkeys which is trying to explain what Branding is&#8230; It&#8217;s quite good. Also, as Nicholas Ind said, there are plenty of definitions of brands and branding. Some people think a brand is a logo. Or advertising. Or packaging. Or another word for the name [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[548],"tags":[34,35,65,66,67],"class_list":["post-4674","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-branding","tag-branding","tag-cristian-saracco","tag-hundred-monkeys","tag-javier-velilla","tag-nicholas-ind"],"_links":{"self":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts\/4674","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/comments?post=4674"}],"version-history":[{"count":0,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts\/4674\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/media\/5544"}],"wp:attachment":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/media?parent=4674"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/categories?post=4674"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/tags?post=4674"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}