{"id":6782,"date":"2016-01-29T18:47:09","date_gmt":"2016-01-29T17:47:09","guid":{"rendered":"https:\/\/allegro234.net\/?p=6782"},"modified":"2026-06-26T21:27:10","modified_gmt":"2026-06-26T19:27:10","slug":"conversaciones-de-marca","status":"publish","type":"post","link":"https:\/\/allegro234.net\/es\/brand-conversations\/","title":{"rendered":"Conversaciones de marca"},"content":{"rendered":"<h4>Construir una experiencia de marca s\u00f3lida y duradera requiere una conversaci\u00f3n personal entre las personas -independientemente de sus funciones- y las organizaciones.<\/h4>\n<blockquote><p>Es una cuesti\u00f3n de valores y creencias en un contexto de debates m\u00e1s amplios.<\/p><\/blockquote>\n<p>La organizaci\u00f3n da una intenci\u00f3n estrat\u00e9gica al di\u00e1logo; sin embargo, es un acontecimiento que escapa a su control. Durante la conversaci\u00f3n a trav\u00e9s de la marca, tanto las empresas como los p\u00fablicos construir\u00e1n una historia compartida que ser\u00e1 relevante, \u00fanica, significativa y familiar si la empresa demuestra coherencia y autenticidad con sus pensamientos, palabras y actos.<\/p>\n<p>De este modo, las personas y las organizaciones encontrar\u00e1n la coherencia y el entusiasmo procedentes de un nuevo tipo de relaci\u00f3n, plausiblemente m\u00e1s colaborativa, basada en conversaciones con conciencia.<\/p>\n<p>Adem\u00e1s, teniendo en cuenta que vivimos en un mundo vol\u00e1til, incierto, complejo y ambiguo -VUCA-, quienes tienen la responsabilidad de dirigir las empresas deben encontrar nuevas formas de mantener di\u00e1logos sencillos y constructivos, al tiempo que responden a los retos de la globalizaci\u00f3n, la digitalizaci\u00f3n y la politizaci\u00f3n:<\/p>\n<ul>\n<li>La globalizaci\u00f3n como intensificaci\u00f3n de las relaciones transnacionales a trav\u00e9s de la interacci\u00f3n entre las personas. El reto es entenderse y obtener reconocimiento, generando una conversaci\u00f3n dotada de significado y relevancia. Es vital comprender los valores entre las personas y la organizaci\u00f3n a trav\u00e9s de la marca.<\/li>\n<li>La digitalizaci\u00f3n como nueva forma de crear y captar valor. Diferentes comunidades est\u00e1n aportando ideas creativas como procesos co-creativos. De alguna manera, en este mundo en red, la clave est\u00e1 en los valores que viven, comparten y comunican impl\u00edcitamente las marcas.<\/li>\n<li>La politizaci\u00f3n de las empresas pasa por lograr un equilibrio entre las demandas de sus p\u00fablicos objetivo en la esfera privada, y su responsabilidad y conciencia sociales. La coherencia de los valores define la autenticidad -no necesariamente la transparencia- de la organizaci\u00f3n en la forma en que aborda estas cuestiones.<\/li>\n<\/ul>\n<p>Para permitir una conversaci\u00f3n profunda, la marca tiene que estar estrat\u00e9gicamente elaborada. La artesan\u00eda evoca la habilidad tradicional, la dedicaci\u00f3n y la perfecci\u00f3n a trav\u00e9s del dominio del detalle. Para el branding, esto significa la necesidad de fusionar la formulaci\u00f3n y la implementaci\u00f3n en un proceso fluido a trav\u00e9s del cual los conceptos creativos de marca evolucionan en nuestro mundo turbulento y disruptivo.<\/p>","protected":false},"excerpt":{"rendered":"<p>Construir una experiencia de marca s\u00f3lida y duradera requiere una conversaci\u00f3n personal entre las personas -independientemente de sus funciones- y las organizaciones.<\/p>","protected":false},"author":2,"featured_media":6784,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[549],"tags":[114,34,291,79,35,39],"class_list":["post-6782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-culture","tag-authenticity","tag-branding","tag-conscience","tag-conversation","tag-cristian-saracco","tag-values"],"_links":{"self":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts\/6782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/comments?post=6782"}],"version-history":[{"count":0,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts\/6782\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/media\/6784"}],"wp:attachment":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/media?parent=6782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/categories?post=6782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/tags?post=6782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}