{"id":7311,"date":"2017-03-07T15:44:54","date_gmt":"2017-03-07T14:44:54","guid":{"rendered":"https:\/\/allegro234.net\/branding-proposito-cuando-se-pone-moda-adan-eva\/"},"modified":"2026-06-26T21:27:09","modified_gmt":"2026-06-26T19:27:09","slug":"proposito-de-marca-adam-eve","status":"publish","type":"post","link":"https:\/\/allegro234.net\/es\/branding-purpose-adam-eve\/","title":{"rendered":"Branding &amp; Purpose | Cuando Ad\u00e1n y Eva se ponen de moda"},"content":{"rendered":"<p>La marca y los fines empresariales son especialmente importantes en tiempos de tensi\u00f3n entre las demandas sociales y lo que se ha dado en llamar la era de la posverdad.<\/p>\n<blockquote><p>Finalidad: De lat. Propos\u012dtum. Una intenci\u00f3n u objetivo; una raz\u00f3n para hacer algo o para permitir que algo suceda.<\/p><\/blockquote>\n<p>En t\u00e9rminos generales, las empresas nacen con una finalidad que da a su existencia un sentido profundo y trascendente. La finalidad responde al \"por qu\u00e9\" de la empresa mucho m\u00e1s all\u00e1 de sus objetivos empresariales.<\/p>\n<p>Hist\u00f3ricamente, en cada momento, y en funci\u00f3n de un contexto determinado, la mayor\u00eda de los que crean una empresa, definen un prop\u00f3sito.<\/p>\n<blockquote><p>Correctamente articulado, el prop\u00f3sito es una fuerte conexi\u00f3n entre el legado y las aspiraciones, en la que se combinan el tiempo de relaci\u00f3n, la intensidad emocional, la intimidad y la reciprocidad entre la organizaci\u00f3n y las personas.<\/p><\/blockquote>\n<p>Tratando de simplificarlo, las diferencias entre las definiciones empresariales cl\u00e1sicas son:<\/p>\n<ul>\n<li>Posicionamiento: \u00bfQu\u00e9 prometo? Lo que ofrece funcionalmente, las razones para creer y lo que la empresa espera que sientan sus p\u00fablicos ante su oferta<\/li>\n<li>Finalidad: \u00bfPor qu\u00e9 existo? A veces supera la raz\u00f3n econ\u00f3mica de la empresa<\/li>\n<li>Los valores: \u00bfCu\u00e1les son mis rasgos culturales? Se traducen en comportamientos que caracterizan a la organizaci\u00f3n<\/li>\n<li>La misi\u00f3n: \u00bfPara qu\u00e9 sirvo? Explica la actividad actual de la empresa y el alcance de dicha actividad: p\u00fablicos clave, geograf\u00edas, etc.<\/li>\n<li>La visi\u00f3n: \u00bfHacia d\u00f3nde me dirijo? Muestra las aspiraciones de las empresas<\/li>\n<li>Idea: \u00bfQu\u00e9 me diferencia del resto? \u00bfQu\u00e9 hace que la empresa sea emocionalmente diferente?<\/li>\n<\/ul>\n<h3>\u00bfHablar de prop\u00f3sito es una moda?<\/h3>\n<p>Hay quien se rasga las vestiduras para demostrar que su prop\u00f3sito es mayor que el del vecino, incluso aprovechando este periodo de posverdad, exagerando la situaci\u00f3n hasta niveles que eliminan cualquier tipo de credibilidad.<\/p>\n<p>La verdad es que muchos hablan de prop\u00f3sito, algunos piensan en el prop\u00f3sito, y pocos son coherentes a la hora de declarar su prop\u00f3sito y darle vida.<\/p>\n<p>La finalidad es tan antigua como el concepto de empresa, sin embargo, no siempre es expl\u00edcita y, en algunos casos, con el paso de los a\u00f1os, se desvanece e incluso cae en el olvido.<\/p>\n<blockquote><p>Prop\u00f3sito no es lo que se hace como RSC, es lo que la empresa hace como parte de su negocio, pero no por hacer negocio.<\/p><\/blockquote>\n<p>Hay varias razones que est\u00e1n reinstalando el prop\u00f3sito en la agenda de la alta direcci\u00f3n:<\/p>\n<ul>\n<li>Convergencia de intereses entre audiencias clave y sociedad en general\n<ul>\n<li>Debido al libro \"<a href=\"http:\/\/sfu.ca\/~wainwrig\/Econ400\/jensen-meckling.pdf\" target=\"_blank\" rel=\"noopener nofollow\">Teor\u00eda de la empresa<\/a>\" escrito por Michael Jensen y William Meckling, en 1976 se produjo un profundo cambio en la concepci\u00f3n de la empresa<\/li>\n<li>Suger\u00eda que entre todos los p\u00fablicos de una empresa, los accionistas ten\u00edan preferencia y que el objetivo de la empresa era maximizar los resultados para ese grupo espec\u00edfico<\/li>\n<li>Esto se implement\u00f3, generaliz\u00f3 y exacerb\u00f3 en el sistema capitalista de los 90. Sin embargo, en la b\u00fasqueda de tales resultados no hubo un control adecuado de las decisiones de los altos ejecutivos, lo que acab\u00f3 convirti\u00e9ndose en una de las causas de la crisis de 2007. As\u00ed lo indicaron <a href=\"http:\/\/wikipedia.org\/wiki\/John_C._Bogle\" target=\"_blank\" rel=\"noopener nofollow\">John C. Bogle<\/a> predicci\u00f3n en 2005<\/li>\n<li>A partir de ese momento, los accionistas han empezado a exigir resultados que vayan m\u00e1s all\u00e1 de los econ\u00f3micos, atendiendo a los impactos sociales y medioambientales<\/li>\n<li>No se trat\u00f3 de un acto de bondad, sino de un reequilibrio de poder en el que los accionistas reconocen que no se trata de ganar m\u00e1s dinero, sino de conseguir mejores resultados, garantizando obviamente que el sistema y quienes lo gestionan est\u00e1n bajo control<\/li>\n<\/ul>\n<\/li>\n<li>Requisito de una sociedad interconectada\n<ul>\n<li>Las nuevas tecnolog\u00edas permiten una reacci\u00f3n global e inmediata, aunque se trate de peque\u00f1os actos y parezcan no tener conexi\u00f3n aparente -el \"efecto mariposa\"-.<\/li>\n<li>No se trata s\u00f3lo de copiar ejemplos de acciones que parten de alg\u00fan lugar del planeta, sino tambi\u00e9n de actuar desde donde alguien est\u00e1 para aportar su granito de arena en pos de un bien superior<\/li>\n<li>Es interesante observar que los acontecimientos no se limitan a la red que interconecta, sino que se transforman en acciones efectivas, por ejemplo en acciones voluntarias concretas o cambios en los patrones de consumo de algunos productos, lo que va m\u00e1s all\u00e1 de las actividades propuestas en internet, como podr\u00edan ser las creadas en change.org<\/li>\n<\/ul>\n<\/li>\n<li>Los rendimientos positivos hacen que las empresas perduren a largo plazo\n<ul>\n<li>Las empresas que act\u00faan conforme a su finalidad obtienen mejores resultados a largo plazo<\/li>\n<li>Un estudio compar\u00f3 las empresas con mayor reputaci\u00f3n con el S&amp;P 500. Se observ\u00f3 que, entre 2006 y 2013, las empresas con un prop\u00f3sito claro y evidente crecieron 75% m\u00e1s que las dem\u00e1s<\/li>\n<li>Adem\u00e1s, el Barrett Values Center demuestra que las empresas que tienen un liderazgo y una cultura reconocidos, integran a sus p\u00fablicos clave y viven su prop\u00f3sito obtienen rendimientos que crecen tres veces m\u00e1s r\u00e1pido que los obtenidos por el S&amp;P 500<\/li>\n<li>Otras m\u00e9tricas de distinto origen indican la misma evoluci\u00f3n<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p style=\"text-align: center\"><a href=\"https:\/\/allegro234.net\/wp-content\/uploads\/2017\/03\/Metricas.png\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter wp-image-7254 size-full\" src=\"https:\/\/allegro234.net\/wp-content\/uploads\/2017\/03\/Metricas.png\" alt=\"\" width=\"1597\" height=\"1068\" title=\"\"><\/a>Diferentes medidas que demuestran que quien tiene un prop\u00f3sito obtiene mejores resultados<\/p>\n<h3>\u00bfPor qu\u00e9 evolucionan los Prop\u00f3sitos?<\/h3>\n<p>Los prop\u00f3sitos son permanentes; sin embargo, sus contenidos evolucionan con el tiempo.<\/p>\n<p>Lo que antes era bueno hoy puede estar mal visto, lo que antes era importante hoy no lo es y viceversa. Piensa en los vegetales transg\u00e9nicos, el uso de combustibles f\u00f3siles, el cambio clim\u00e1tico o la igualdad entre hombres y mujeres.<\/p>\n<p>Hoy, las empresas de nueva creaci\u00f3n tienen la ventaja de que quienes las crean -especialmente los Millennials- ya han incorporado dos temas que est\u00e1n relacionados y son complementarios:<\/p>\n<ul>\n<li>Entienden que los negocios deben nacer con un prop\u00f3sito, aunque no necesariamente consideren que la empresa los trascender\u00e1 en el tiempo<\/li>\n<li>La finalidad debe considerar tanto un resultado econ\u00f3mico como un impacto positivo demostrable y medible<\/li>\n<\/ul>\n<p>Para las empresas que llevan varios a\u00f1os en el mercado, se trata de redescubrir su prop\u00f3sito, actualizarlo y darle vida de forma eficaz.<\/p>\n<p>Las empresas guiadas por un prop\u00f3sito saben y reconocen que est\u00e1n inmersas en cambios en un contexto turbulento, ambiguo, incierto y complejo al que deben estar atentas, porque es ah\u00ed donde se generan los requisitos de adecuaci\u00f3n.<\/p>\n<h3>La marca habla de prop\u00f3sito, \u00bftiene sentido?<\/h3>\n<p>La marca tambi\u00e9n ha evolucionado desde sus primeras apariciones hace m\u00e1s de 9.000 a\u00f1os -los primeros registros hist\u00f3ricos se remontan a marcas, s\u00edmbolos y signos encontrados en las ruinas de las grandes ciudades de Mesopotamia-.<\/p>\n<p>La profesionalizaci\u00f3n de su gesti\u00f3n, desde <a href=\"http:\/\/www.brandingstrategyinsider.com\/2009\/06\/great-moments-in-branding-neil-mcelroy-memo.html\" target=\"_blank\" rel=\"noopener nofollow\">Nota de Neil McElroy<\/a> en 1931 hasta la fecha tambi\u00e9n ha mostrado su evoluci\u00f3n.<\/p>\n<blockquote><p>La marca ha pasado de ser una herramienta de marketing a convertirse en una plataforma empresarial estrat\u00e9gica, de la gesti\u00f3n de marca al liderazgo de marca.<\/p><\/blockquote>\n<p>Por ejemplo, cuando vemos la \"Sirena de Starbucks\", adem\u00e1s de poder imaginar la experiencia que nos ofrecer\u00e1n en cuanto a productos, precios, comodidad, espacio o atenci\u00f3n, empezamos a a\u00f1adir cuestiones como valores y principios, comercio justo, esfuerzos internos de aprendizaje, acciones sociales, ambiciones empresariales, historia y legado.<\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/allegro234.net\/wp-content\/uploads\/2017\/03\/b2b_starbucks_logo-evolution.jpg\"><img decoding=\"async\" class=\"aligncenter size-medium wp-image-7252\" src=\"https:\/\/allegro234.net\/wp-content\/uploads\/2017\/03\/b2b_starbucks_logo-evolution-300x92.jpg\" alt=\"\" width=\"420\" height=\"129\" title=\"\"><\/a>La evoluci\u00f3n de la marca Starbucks<\/p>\n<p>Todas estas cuestiones est\u00e1n alineadas con la estrategia corporativa y llevan a considerar la marca como s\u00edntesis y catalizador de lo que la empresa fue, es y ser\u00e1. La marca es el nexo intuitivo que permite establecer conversaciones entre personas y organizaciones, y esto es previo al \u00fatil y necesario aspecto transaccional requerido para cerrar una venta.<\/p>\n<h3>Marcas con Conciencia, \u00bfSon como Teresa de Calcuta o Parte del Realismo M\u00e1gico de Borges?<\/h3>\n<p>Como \"effeuiller la marguerite\" -me quiere, no me quiere-, hay marcas que transmiten prop\u00f3sitos que nos gustan y otras que no.<\/p>\n<p>Esto no significa que el camino que ha decidido seguir la empresa sea el correcto. Deber\u00edamos prestar atenci\u00f3n y descubrir si existe alg\u00fan tipo de activismo empresarial pragm\u00e1tico, si se persigue un verdadero resultado tanto social y medioambiental como econ\u00f3mico.<\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/allegro234.net\/wp-content\/uploads\/2017\/03\/JedisLado-oscuro.png\"><img decoding=\"async\" class=\"aligncenter wp-image-7253\" src=\"https:\/\/allegro234.net\/wp-content\/uploads\/2017\/03\/JedisLado-oscuro-480x237.png\" alt=\"\" width=\"304\" height=\"150\" title=\"\"><\/a><\/p>\n<p style=\"text-align: center\">Escudos de la Rep\u00fablica Gal\u00e1ctica y de la Confederaci\u00f3n de Sistemas Independientes<\/p>\n<p>Veamos las dos caras de la moneda:<\/p>\n<ul>\n<li>Los Jedis: De Tony's Chocolonely -chocolate holand\u00e9s sin esclavitud infantil- a <a href=\"http:\/\/www.unilever.com\" target=\"_blank\" rel=\"noopener nofollow\">Unilever<\/a> tienen un prop\u00f3sito, ejercen cierto activismo pragm\u00e1tico, incluso su <a href=\"http:\/\/www.benjerry.co.uk\" target=\"_blank\" rel=\"noopener nofollow\">Ben &amp; Jerry's<\/a> unidad va mucho m\u00e1s all\u00e1, y sus marcas lo transmiten. Las empresas de moda -un ox\u00edmoron en este tema, como <a href=\"http:\/\/www.stellamccartney.com\" target=\"_blank\" rel=\"noopener nofollow\">Stella McCartney<\/a> o <a href=\"http:\/\/www.viviennewestwood.com\" target=\"_blank\" rel=\"noopener nofollow\">Vivienne Westwood<\/a> son fieles a su prop\u00f3sito; <a href=\"http:\/\/www.hm.com\" target=\"_blank\" rel=\"noopener nofollow\">H&amp;M<\/a> est\u00e1 en el camino de la econom\u00eda 360<\/li>\n<li>Abandonar el lado oscuro de la fuerza: <a href=\"http:\/\/dupont.com\" target=\"_blank\" rel=\"noopener nofollow\">DuPont<\/a> produce y vende Neopreno, Nylon, Tefl\u00f3n, Lycra o Kevlar, productos cuya biodegradaci\u00f3n es casi nula. Desde 2003 tambi\u00e9n ofrece productos que no da\u00f1an la atm\u00f3sfera, ha desarrollado el Sorona, un pol\u00edmero obtenido a partir del almid\u00f3n de ma\u00edz -org\u00e1nico y biodegradable-. Su activismo es menor que el de los Jedis, sin embargo, su finalidad ha renacido y se est\u00e1 adaptando a las exigencias de una nueva realidad.<\/li>\n<\/ul>\n<p>Pueden ser alabados o criticados -en algunos casos muy criticados-, lo relevante en este momento es que est\u00e1n haciendo algo positivo. Debemos saber equilibrar el deseo con la posibilidad, la aspiraci\u00f3n con la realidad, el idealismo con el sentido pr\u00e1ctico.<\/p>\n<p>El viaje no ha hecho m\u00e1s que empezar; quiz\u00e1 la clave est\u00e9 en encontrar al compa\u00f1ero adecuado para vivir esta gran aventura.<\/p>\n<blockquote><p>Ni el m\u00e1s guay, ni el m\u00e1s grande, ni el que habla demasiado... Se trata de recorrer el camino que gu\u00eda tu prop\u00f3sito con aquellos que piensan, dicen y hacen de forma coherente.<\/p><\/blockquote>","protected":false},"excerpt":{"rendered":"<p>Correctamente articulado, el prop\u00f3sito es una fuerte conexi\u00f3n entre el legado y las aspiraciones, en la que se combinan el tiempo de relaci\u00f3n, la intensidad emocional, la intimidad y la reciprocidad entre la organizaci\u00f3n y las personas<\/p>","protected":false},"author":2,"featured_media":7255,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[548],"tags":[372],"class_list":["post-7311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-branding","tag-crafted-branding"],"_links":{"self":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts\/7311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/comments?post=7311"}],"version-history":[{"count":0,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/posts\/7311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/media\/7255"}],"wp:attachment":[{"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/media?parent=7311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/categories?post=7311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/allegro234.net\/es\/wp-json\/wp\/v2\/tags?post=7311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}